{"id":3684,"date":"2014-12-17T05:21:01","date_gmt":"2014-12-17T05:21:01","guid":{"rendered":"http:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png"},"modified":"2014-12-17T05:21:01","modified_gmt":"2014-12-17T05:21:01","slug":"pittsburgh-fire-hydrant-summer","status":"inherit","type":"attachment","link":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/2012\/12\/05\/wrench-keeper-jennie-karlovich-makes-a-real-splash-in-her-civic-duty\/pittsburgh-fire-hydrant-summer\/","title":{"rendered":"Pittsburgh fire hydrant summer"},"author":5,"comment_status":"closed","ping_status":"open","template":"","meta":[],"acf":[],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?ssl=1\" data-rel=\"lightbox-gallery-pZaYKZ66\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img width=\"300\" height=\"204\" src=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=300%2C204&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?w=691&amp;ssl=1 691w, https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?resize=512%2C350&amp;ssl=1 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"3684\" data-permalink=\"https:\/\/newsinteractive.post-gazette.com\/thedigs\/2012\/12\/05\/wrench-keeper-jennie-karlovich-makes-a-real-splash-in-her-civic-duty\/pittsburgh-fire-hydrant-summer\/\" data-orig-file=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=691%2C472&amp;ssl=1\" data-orig-size=\"691,472\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Pittsburgh fire hydrant summer\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=300%2C204&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=691%2C472&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a class='more-link' href='https:\/\/newsinteractive.post-gazette.com\/thedigs\/2012\/12\/05\/wrench-keeper-jennie-karlovich-makes-a-real-splash-in-her-civic-duty\/pittsburgh-fire-hydrant-summer\/'>Look at the pictures<span class='screen-reader-text'>Pittsburgh fire hydrant summer<\/span><\/a><\/p>"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":691,"height":472,"file":"2012\/12\/Pittsburgh-fire-hydrant-summer.png","sizes":{"thumbnail":{"file":"Pittsburgh-fire-hydrant-summer-630x255.png","width":630,"height":255,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?resize=630%2C255&ssl=1"},"medium":{"file":"Pittsburgh-fire-hydrant-summer-300x204.png","width":300,"height":204,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=300%2C204&ssl=1"},"blog":{"file":"Pittsburgh-fire-hydrant-summer-512x350.png","width":512,"height":350,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=512%2C350&ssl=1"},"guest-author-32":{"file":"Pittsburgh-fire-hydrant-summer-32x32.png","width":32,"height":32,"mime_type":"image\/png","source_url":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer-32x32.png"},"guest-author-64":{"file":"Pittsburgh-fire-hydrant-summer-64x64.png","width":64,"height":64,"mime_type":"image\/png","source_url":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer-64x64.png"},"guest-author-96":{"file":"Pittsburgh-fire-hydrant-summer-96x96.png","width":96,"height":96,"mime_type":"image\/png","source_url":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer-96x96.png"},"guest-author-128":{"file":"Pittsburgh-fire-hydrant-summer-128x128.png","width":128,"height":128,"mime_type":"image\/png","source_url":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer-128x128.png"},"full":{"file":"Pittsburgh-fire-hydrant-summer.png?fit=691%2C472&ssl=1","width":691,"height":472,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png?fit=691%2C472&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":2230,"source_url":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-content\/uploads\/2012\/12\/Pittsburgh-fire-hydrant-summer.png","_links":{"self":[{"href":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-json\/wp\/v2\/media\/3684"}],"collection":[{"href":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinteractive.post-gazette.com\/thedigs\/wp-json\/wp\/v2\/comments?post=3684"}]}}